{"id":152090,"date":"2026-05-12T20:29:26","date_gmt":"2026-05-12T23:29:26","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg"},"modified":"2026-05-12T20:29:26","modified_gmt":"2026-05-12T23:29:26","slug":"invitacion-acto-130-anos-santa-teresa-de-jesus-3","status":"inherit","type":"attachment","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/130-anos-de-mision-aniversario-del-instituto-santa-teresa-de-jesus\/invitacion-acto-130-anos-santa-teresa-de-jesus-3\/","title":{"rendered":"invitacion acto 130 a\u00f1os Santa Teresa de Jesus 3"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-152090","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"192\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg 2048w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-634x420.jpg 634w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-696x461.jpg 696w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1068x707.jpg 1068w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1920x1271.jpg 1920w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1356,"file":"2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg","filesize":246347,"sizes":{"td_0x420":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-634x420.jpg","width":634,"height":420,"filesize":39194,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-634x420.jpg"},"td_80x60":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-80x60.jpg","width":80,"height":60,"filesize":2300,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-80x60.jpg"},"td_218x150":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-218x150.jpg","width":218,"height":150,"filesize":8078,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-218x150.jpg"},"td_324x400":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x400.jpg","width":324,"height":400,"filesize":20710,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x400.jpg"},"td_485x360":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-485x360.jpg","width":485,"height":360,"filesize":27746,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-485x360.jpg"},"td_696x0":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-696x461.jpg","width":696,"height":461,"filesize":44975,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-696x461.jpg"},"td_1068x0":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1068x707.jpg","width":1068,"height":707,"filesize":87747,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1068x707.jpg"},"td_1920x0":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1920x1271.jpg","width":1920,"height":1271,"filesize":216654,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1920x1271.jpg"},"td_100x70":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-100x70.jpg","width":100,"height":70,"filesize":2959,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-100x70.jpg"},"td_265x198":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-265x198.jpg","width":265,"height":198,"filesize":11308,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-265x198.jpg"},"td_324x160":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x160.jpg","width":324,"height":160,"filesize":10650,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x160.jpg"},"td_324x235":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x235.jpg","width":324,"height":235,"filesize":15025,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-324x235.jpg"},"td_356x220":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-356x220.jpg","width":356,"height":220,"filesize":15368,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-356x220.jpg"},"td_356x364":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-356x364.jpg","width":356,"height":364,"filesize":21376,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-356x364.jpg"},"td_533x261":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-533x261.jpg","width":533,"height":261,"filesize":22372,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-533x261.jpg"},"td_534x462":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-534x462.jpg","width":534,"height":462,"filesize":35509,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-534x462.jpg"},"td_696x385":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-696x385.jpg","width":696,"height":385,"filesize":38282,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-696x385.jpg"},"td_741x486":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-741x486.jpg","width":741,"height":486,"filesize":49221,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-741x486.jpg"},"td_1068x580":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1068x580.jpg","width":1068,"height":580,"filesize":71757,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3-1068x580.jpg"},"full":{"file":"invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg","width":2048,"height":1356,"mime_type":"image\/jpeg","source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":152087,"source_url":"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/invitacion-acto-130-anos-Santa-Teresa-de-Jesus-3.jpg","_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/152090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}]}}