{"id":153054,"date":"2026-05-22T11:31:43","date_gmt":"2026-05-22T14:31:43","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=153054"},"modified":"2026-05-22T11:31:44","modified_gmt":"2026-05-22T14:31:44","slug":"estrellas-amarillas-homenajeo-a-victimas-de-siniestros-viales-y-profundizo-en-la-concientizacion-con-estudiantes-de-goya","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/estrellas-amarillas-homenajeo-a-victimas-de-siniestros-viales-y-profundizo-en-la-concientizacion-con-estudiantes-de-goya\/","title":{"rendered":"ESTRELLAS AMARILLAS HOMENAJE\u00d3 A V\u00cdCTIMAS DE SINIESTROS VIALES Y PROFUNDIZ\u00d3 EN LA CONCIENTIZACI\u00d3N CON ESTUDIANTES DE GOYA"},"content":{"rendered":"<p>La ONG realiz\u00f3 actividades junto a familiares y estudiantes del Colegio Torrent, en una semana marcada por la memoria, el acompa\u00f1amiento y la educaci\u00f3n vial. Se repintaron dos estrellas y se rindieron homenaje a ambas v\u00edctimas.<a href=\"https:\/\/revistaesperanzas.com\/web\/2026\/05\/estrellas-amarillas-homenajeo-a-victimas-de-siniestros-viales-y-profundizo-en-la-concientizacion-con-estudiantes-de-goya\/homenaje-a-trinidad-brito-fallecio-el-2-5-24-este-20-de-mayo-de-2026-repintaron-su-estrella\/\" rel=\"attachment wp-att-153056\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-153056 alignleft\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella.jpg\" alt=\"\" width=\"531\" height=\"372\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella.jpg 600w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella-100x70.jpg 100w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/a><\/p>\n<p>La organizaci\u00f3n Estrellas Amarillas Goya llev\u00f3 adelante durante esta semana homenajes y actividades de concientizaci\u00f3n vial en distintos puntos de la ciudad, recordando a v\u00edctimas de siniestros viales y promoviendo la educaci\u00f3n y prevenci\u00f3n entre j\u00f3venes estudiantes.<\/p>\n<p>Uno de los encuentros se realiz\u00f3 frente al edificio del Colegio Torrent, por calle Belgrano entre Sargento Cabral y Baibiene donde familiares e integrantes de la ONG encabezados por Viviana Canaparro, la referente en Goya, participaron del repintado de la estrella amarilla en memoria de Dora Flores, fallecida en 1982.<\/p>\n<p>La actividad cont\u00f3 con el acompa\u00f1amiento del inspector Gustavo Clemente y la<a href=\"https:\/\/revistaesperanzas.com\/web\/2026\/05\/estrellas-amarillas-homenajeo-a-victimas-de-siniestros-viales-y-profundizo-en-la-concientizacion-con-estudiantes-de-goya\/homenaje-a-trinidad-brito-fallecio-el-2-5-24-este-20-de-mayo-de-2026-repintaron-su-estrella-2\/\" rel=\"attachment wp-att-153057\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-153057 alignright\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella-.jpg\" alt=\"\" width=\"380\" height=\"532\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella-.jpg 500w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Homenaje-a-Trinidad-Brito-Fallecio-el-2-5-24-Este-20-de-Mayo-de-2026-repintaron-su-estrella--300x420.jpg 300w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a> participaci\u00f3n de alumnos de primer a\u00f1o de la instituci\u00f3n educativa junto a sus docentes.<\/p>\n<p>MEMORIA Y CONCIENTIZACI\u00d3N<\/p>\n<p>Durante la jornada, adem\u00e1s del homenaje simb\u00f3lico, se brind\u00f3 una charla de seguridad vial destinada a los estudiantes, con el objetivo de generar conciencia sobre la importancia del respeto a las normas de tr\u00e1nsito y la prevenci\u00f3n de accidentes.<\/p>\n<p>Asimismo, el mi\u00e9rcoles 20 de mayo se realiz\u00f3 otro emotivo acto al cumplirse dos a\u00f1os del fallecimiento de la joven Trinidad Brito quien, con tan solo 17 a\u00f1os perdi\u00f3 la vida en avenida Per\u00f3n y calle Alemania. Su madre, familiares y amigos repintaron la estrella amarilla colocada en el lugar del hecho para mantener viva su memoria.<\/p>\n<p>En ambas actividades estuvo presente Viviana Canaparro, referente local de Estrellas Amarillas, acompa\u00f1ando a las familias y reafirmando el compromiso de la organizaci\u00f3n con la educaci\u00f3n vial y el acompa\u00f1amiento a las v\u00edctimas.<a href=\"https:\/\/revistaesperanzas.com\/web\/2026\/05\/estrellas-amarillas-homenajeo-a-victimas-de-siniestros-viales-y-profundizo-en-la-concientizacion-con-estudiantes-de-goya\/estrellas-amarillas-goya-concientizacion-con-estudiantes-del-colegio-torrent\/\" rel=\"attachment wp-att-153058\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-153058 alignleft\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Estrellas-Amarillas-Goya-Concientizacion-con-estudiantes-del-colegio-Torrent.jpeg\" alt=\"\" width=\"530\" height=\"371\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Estrellas-Amarillas-Goya-Concientizacion-con-estudiantes-del-colegio-Torrent.jpeg 600w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Estrellas-Amarillas-Goya-Concientizacion-con-estudiantes-del-colegio-Torrent-100x70.jpeg 100w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/a><\/p>\n<p>RECONOCIMIENTO NACIONAL<\/p>\n<p>Desde la ONG tambi\u00e9n destacaron que Estrellas Amarillas Goya fue invitada a participar de un Congreso Nacional de la organizaci\u00f3n, tras ser seleccionada por el trabajo y los proyectos que desarrolla a nivel nacional en materia de prevenci\u00f3n y concientizaci\u00f3n vial.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ONG realiz\u00f3 actividades junto a familiares y estudiantes del Colegio Torrent, en una semana marcada por la memoria, el acompa\u00f1amiento y la educaci\u00f3n vial. Se repintaron dos estrellas y se rindieron homenaje a ambas v\u00edctimas. La organizaci\u00f3n Estrellas Amarillas Goya llev\u00f3 adelante durante esta semana homenajes y actividades de concientizaci\u00f3n vial en distintos puntos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":153055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-153054","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=153054"}],"version-history":[{"count":0,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/153055"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=153054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=153054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=153054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}