{"id":153252,"date":"2026-05-27T11:35:41","date_gmt":"2026-05-27T14:35:41","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=153252"},"modified":"2026-05-27T11:35:41","modified_gmt":"2026-05-27T14:35:41","slug":"ituzaingo-en-un-allanamiento-efectuado-por-las-policia-de-corrientes-encuentran-y-secuestran-varios-elementos-que-fueran-robados","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/ituzaingo-en-un-allanamiento-efectuado-por-las-policia-de-corrientes-encuentran-y-secuestran-varios-elementos-que-fueran-robados\/","title":{"rendered":"ITUZAINGO; EN UN ALLANAMIENTO EFECTUADO POR LAS POLIC\u00cdA DE CORRIENTES, ENCUENTRAN Y SECUESTRAN VARIOS ELEMENTOS QUE FUERAN ROBADOS"},"content":{"rendered":"<p>La Polic\u00eda tras diligenciar \u00f3rdenes de allanamientos permiti\u00f3 recuperar elementos que fueran sustra\u00eddos<\/p>\n<p>Ayer 26-05-26, efectivos policiales de la Comisaria de distrito primera de Ituzaing\u00f3, en colaboraci\u00f3n con la unidad fiscal interviniente, en el marco de tareas investigativas relacionadas a un il\u00edcito, tras diligenciar dos \u00f3rdenes de allanamientos permiti\u00f3 recuperar varios elementos denunciados como sustra\u00eddos.<\/p>\n<p>La investigaci\u00f3n se inici\u00f3 tras la denuncia radicada por una mujer, que habr\u00eda sido v\u00edctima de la sustracci\u00f3n de varias cosas de su domicilio ubicado en el barrio Villa Luisa de la ciudad de Ituzaing\u00f3.<\/p>\n<p>Como resultado de las pesquisas, se dio cumplimiento a las \u00f3rdenes de allanamiento, efectuadas en domicilios ubicados por calle Entre R\u00edos y Brasil, propiedad de un hombre de 34 a\u00f1os; y en una vivienda situada por calle Francisco L\u00f3pez y Ant\u00e1rtida Argentina, donde reside un joven, de 17 a\u00f1os de edad.<\/p>\n<p>Durante los procedimientos se logr\u00f3 el secuestro de diversos elementos vinculados a la causa, entre ellos una cartera color marr\u00f3n con una billetera del mismo color en su interior, documentaci\u00f3n y sellos pertenecientes a la denunciante, adem\u00e1s de un tensi\u00f3metro, un parlante de sonido, un casco de seguridad y una termera, objetos que se tratar\u00edan de los denunciados como sustra\u00eddos.<\/p>\n<p>Los elementos recuperados fueron puestos a disposici\u00f3n de la autoridad judicial interviniente, continu\u00e1ndose con las diligencias y tr\u00e1mites de rigor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda tras diligenciar \u00f3rdenes de allanamientos permiti\u00f3 recuperar elementos que fueran sustra\u00eddos Ayer 26-05-26, efectivos policiales de la Comisaria de distrito primera de Ituzaing\u00f3, en colaboraci\u00f3n con la unidad fiscal interviniente, en el marco de tareas investigativas relacionadas a un il\u00edcito, tras diligenciar dos \u00f3rdenes de allanamientos permiti\u00f3 recuperar varios elementos denunciados como sustra\u00eddos. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":153253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-153252","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corrientes"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=153252"}],"version-history":[{"count":0,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/153253"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=153252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=153252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=153252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}