{"id":153317,"date":"2026-05-27T21:56:29","date_gmt":"2026-05-28T00:56:29","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=153317"},"modified":"2026-05-27T21:56:29","modified_gmt":"2026-05-28T00:56:29","slug":"empedrado-policia-recupera-bicicletas-denunciadas-como-robadas","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/empedrado-policia-recupera-bicicletas-denunciadas-como-robadas\/","title":{"rendered":"EMPEDRADO: POLICIA RECUPERA BICICLETAS DENUNCIADAS COMO ROBADAS"},"content":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito Empedrado, en colaboraci\u00f3n a la Unidad Fiscal interviniente y en el marco de distintas causas judiciales en curso, referentes a la sustracci\u00f3n de dos bicicletas, tras realizar una eficaz labor de investigaci\u00f3n, lograron recuperar los rodados.<\/p>\n<p>Los distintos procedimientos fueron realizados por los citados efectivos junto a sus pares del \u00c1rea de Investigaci\u00f3n Criminal, quienes, luego de tomar conocimiento de los il\u00edcitos, realizaron distintas labores de b\u00fasqueda y recolecci\u00f3n de informaci\u00f3n, lo que posibilito hallar y recuperar dos bicicletas de distintas marcas, las cuales, tras las correspondientes averiguaciones, resultaron ser las denunciadas como sustra\u00eddas.<\/p>\n<p>Posteriormente, los rodados recuperados fueron puestos a disposici\u00f3n de la justicia y trasladados a la citada dependencia, donde se continuaron con los tramites al respecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito Empedrado, en colaboraci\u00f3n a la Unidad Fiscal interviniente y en el marco de distintas causas judiciales en curso, referentes a la sustracci\u00f3n de dos bicicletas, tras realizar una eficaz labor de investigaci\u00f3n, lograron recuperar los rodados. Los distintos procedimientos fueron realizados por los citados efectivos junto a sus pares [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":153319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-153317","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corrientes"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=153317"}],"version-history":[{"count":0,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/153319"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=153317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=153317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=153317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}