{"id":153321,"date":"2026-05-27T21:59:13","date_gmt":"2026-05-28T00:59:13","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=153321"},"modified":"2026-05-27T21:59:13","modified_gmt":"2026-05-28T00:59:13","slug":"paso-de-los-libres-policia-recupera-bicicleta-robada-y-detiene-al-autor-del-hecho","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/paso-de-los-libres-policia-recupera-bicicleta-robada-y-detiene-al-autor-del-hecho\/","title":{"rendered":"PASO DE LOS LIBRES: POLICIA RECUPERA BICICLETA ROBADA Y DETIENE AL AUTOR DEL HECHO"},"content":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito 2da. De Paso de los Libres, en el marco de una causa judicial que se investiga por \u2013 supuesto Hurto- con la intervenci\u00f3n de la Unidad Fiscal, luego de realizar una eficaz tarea de investigaci\u00f3n, lograron identificar al presunto autor del hecho y recuperar una bicicleta, la cual, fuera denunciada como sustra\u00edda.<\/p>\n<p>El procedimiento fue realizado por los citados efectivos luego de tomar conocimiento de la sustracci\u00f3n de una bicicleta \u2013 marca Kuwara, rodado 29\u201d-, por lo que, tras varias tareas investigativas, lograron identificar a un joven menor de edad, quien estar\u00eda sindicado como presunto autor del hecho, adem\u00e1s, recuperaron el rodado denunciado como sustra\u00eddo.<\/p>\n<p>La bicicleta recuperada fue puesta a disposici\u00f3n de las autoridades judiciales correspondientes y trasladada a la citada dependencia, donde se continuaron con los tramites de rigor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito 2da. De Paso de los Libres, en el marco de una causa judicial que se investiga por \u2013 supuesto Hurto- con la intervenci\u00f3n de la Unidad Fiscal, luego de realizar una eficaz tarea de investigaci\u00f3n, lograron identificar al presunto autor del hecho y recuperar una bicicleta, la cual, fuera [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":153322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-153321","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corrientes"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=153321"}],"version-history":[{"count":0,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/153322"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=153321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=153321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=153321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}