{"id":153357,"date":"2026-05-28T22:24:47","date_gmt":"2026-05-29T01:24:47","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=153357"},"modified":"2026-05-28T22:24:47","modified_gmt":"2026-05-29T01:24:47","slug":"la-comision-de-saludo-del-h-c-d-de-goya-recibio-al-secretario-de-modernizacion","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/05\/la-comision-de-saludo-del-h-c-d-de-goya-recibio-al-secretario-de-modernizacion\/","title":{"rendered":"LA COMISION DE SALUDO DEL &#8220;H.C.D. de GOYA&#8221; RECIBI\u00d3 AL SECRETARIO DE MODERNIZACI\u00d3N"},"content":{"rendered":"<p>Este jueves, en el Sal\u00f3n \u201cMabel Barrile\u201d del Concejo Deliberante local, los integrantes de la Comisi\u00f3n de Salud se reunieron con el secretario de Modernizaci\u00f3n de la Municipalidad de Goya, Andr\u00e9s Zajarevich, con quien analizaron el proyecto sobre \u201cDigitalizaci\u00f3n del sistema de turnos en los centros de salud\u201d dependientes de la comuna.<\/p>\n<p>Conformaron esta comisi\u00f3n los concejales Gabriela Refojos, Susana Quiroz, Sabina Valeria Calvi, Ver\u00f3nica Ram\u00edrez y Antonio Mazzaro, en tanto que Yanina Clarisa Delgado de la Secretar\u00eda de Comisiones del HCD brind\u00f3 asistencia t\u00e9cnica a los ediles.<\/p>\n<p>En esta oportunidad, los ediles miembros de esta Comisi\u00f3n de Salud se abocaron al estudio del Expediente 3490, proyecto de Ordenanza sobre \u201cDigitalizaci\u00f3n del sistema de turno en los centros de salud&#8221; con la participaci\u00f3n del secretario de Modernizaci\u00f3n, Innovaci\u00f3n y Desarrollo Tecnol\u00f3gico, Andr\u00e9s Zajarevich.<a href=\"https:\/\/revistaesperanzas.com\/web\/2026\/05\/la-comision-de-saludo-del-h-c-d-de-goya-recibio-al-secretario-de-modernizacion\/comision-de-salud-recibio-al-secretario-de-modernizacion-andres-zajarevich-2\/\" rel=\"attachment wp-att-153359\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-153359\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Comision-de-Salud-recibio-al-Secretario-de-Modernizacion-Andres-Zajarevich-.jpg\" alt=\"\" width=\"699\" height=\"489\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Comision-de-Salud-recibio-al-Secretario-de-Modernizacion-Andres-Zajarevich-.jpg 600w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/05\/Comision-de-Salud-recibio-al-Secretario-de-Modernizacion-Andres-Zajarevich--100x70.jpg 100w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/a><\/p>\n<p>Los ediles interiorizaron al funcionario sobre la finalidad que persigue el proyecto en cuesti\u00f3n. \u201cNo queremos que la gente siga esperando con el frio y despu\u00e9s no conseguir que se los atienda\u201d, manifestaron.<\/p>\n<p>En tanto, el contador Zajarevich, inform\u00f3 que el Ejecutivo Municipal est\u00e1 trabajando con una empresa tecnol\u00f3gica afincada en Goya, en una aplicaci\u00f3n para implementar -en poco tiempo m\u00e1s-, un sistema digital de seguimiento de salud para la atenci\u00f3n de los vecinos.<\/p>\n<p>\u201cEs una aplicaci\u00f3n que incluye muchas cosas, incluso poder sacar turnos\u201d, asegur\u00f3 el secretario de Modernizaci\u00f3n. Y adelant\u00f3 que la semana que viene podr\u00eda estar ya en funcionamiento el nuevo sistema digital.<\/p>\n<p>Zajarevich se comprometi\u00f3 adem\u00e1s a enviar a la comisi\u00f3n un informe detallado de todo lo que va a contener la aplicaci\u00f3n digital que implementar\u00e1 el Municipio pr\u00f3ximamente. Los integrantes de la comisi\u00f3n de Salud, acordaron tambi\u00e9n invitar al subsecretario de Salud, doctor Emilio Mart\u00ednez para el 11 de junio, a las 9 hs, a efectos de esclarecer algunas dudas sobre el futuro sistema digital de seguimiento de salud de atenci\u00f3n a los vecinos.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves, en el Sal\u00f3n \u201cMabel Barrile\u201d del Concejo Deliberante local, los integrantes de la Comisi\u00f3n de Salud se reunieron con el secretario de Modernizaci\u00f3n de la Municipalidad de Goya, Andr\u00e9s Zajarevich, con quien analizaron el proyecto sobre \u201cDigitalizaci\u00f3n del sistema de turnos en los centros de salud\u201d dependientes de la comuna. Conformaron esta comisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":153358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-153357","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=153357"}],"version-history":[{"count":0,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/153357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/153358"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=153357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=153357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=153357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}