{"id":158601,"date":"2026-07-14T19:30:12","date_gmt":"2026-07-14T22:30:12","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=158601"},"modified":"2026-07-14T19:30:12","modified_gmt":"2026-07-14T22:30:12","slug":"mercedes-comisaria-de-la-mujer-y-el-menor","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/07\/mercedes-comisaria-de-la-mujer-y-el-menor\/","title":{"rendered":"MERCEDES &#8211; COMISARIA DE LA MUJER Y EL MENOR"},"content":{"rendered":"<p>SOLICITUD DE COLABORACION PARA LA LOCALIZACION Y PARADERO DE LA MENOR CASTRO RITA EMILIA SOLEDAD DE 17 A\u00d1OS DE EDAD<\/p>\n<p>A trav\u00e9s de la presente Gacetilla, solicitamos a los distintos medios de comunicaci\u00f3n pueda ser reflejado-publicado sobre una solicitud enviada desde la Comisar\u00eda de Mujer y<a href=\"https:\/\/revistaesperanzas.com\/web\/2026\/07\/mercedes-comisaria-de-la-mujer-y-el-menor\/whatsapp-image-2026-07-14-at-09-10-17\/\" rel=\"attachment wp-att-158602\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-158602 alignleft\" src=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-09.10.17.jpeg\" alt=\"\" width=\"400\" height=\"560\" srcset=\"https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-09.10.17.jpeg 500w, https:\/\/revistaesperanzas.com\/web\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-09.10.17-300x420.jpeg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a> el Menor de Mercedes, quienes solicitan la colaboraci\u00f3n para dar difusi\u00f3n respecto a la b\u00fasqueda y localizaci\u00f3n de una menor identificada como CASTRO RITA EMILIA SOLEDAD DE 17 A\u00d1OS DE EDAD, quien conforme a la denuncia efectuada por una persona -apellido Maidana-, la misma se habr\u00eda ausentado desde el pasado 12-07-26, dando intervenci\u00f3n de \u00e9sta situaci\u00f3n tambi\u00e9n a la fiscal\u00eda de Investigaci\u00f3n en turno.<\/p>\n<p>Sus caracter\u00edsticas f\u00edsicas son las siguientes: de t\u00e9s blanca, de aprox. 1,60 de estatura, contextura robusta, de cabello casta\u00f1o largo lacio. SE\u00d1A PARTICULAR: posee una cicatriz peque\u00f1a en la frente y usa anteojos.<\/p>\n<p>Es por ello, que independientemente de la labor de b\u00fasqueda que \u00e9sta realizando la Polic\u00eda, se solicita la colaboraci\u00f3n a los distintos medios period\u00edsticos para su publicaci\u00f3n y de esa manera dar a conocer a la poblaci\u00f3n en general, para que aquellas personas que puedan aportar datos ciertos y que ayuden a lograr encontrar a esta menor, puedan hacerlo ante la citada Comisar\u00eda de la Mujer y el Menor nro. 3794-950990; o la Dependencia Policial m\u00e1s cercana a su domicilio y\/o comunicarse al n\u00famero telef\u00f3nico gratuito del Sistema Integral de Seguridad (S.I.S.) 911 en la Capital y 101 en el Interior Provincial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOLICITUD DE COLABORACION PARA LA LOCALIZACION Y PARADERO DE LA MENOR CASTRO RITA EMILIA SOLEDAD DE 17 A\u00d1OS DE EDAD A trav\u00e9s de la presente Gacetilla, solicitamos a los distintos medios de comunicaci\u00f3n pueda ser reflejado-publicado sobre una solicitud enviada desde la Comisar\u00eda de Mujer y el Menor de Mercedes, quienes solicitan la colaboraci\u00f3n para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":158603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-158601","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corrientes"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=158601"}],"version-history":[{"count":2,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158601\/revisions"}],"predecessor-version":[{"id":158605,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158601\/revisions\/158605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/158603"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=158601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=158601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=158601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}