{"id":158610,"date":"2026-07-14T21:27:47","date_gmt":"2026-07-15T00:27:47","guid":{"rendered":"https:\/\/revistaesperanzas.com\/web\/?p=158610"},"modified":"2026-07-14T21:27:47","modified_gmt":"2026-07-15T00:27:47","slug":"saladas-policia-de-corrientes-secuestra-motocicleta-con-pedido-de-secuestro-activo","status":"publish","type":"post","link":"https:\/\/revistaesperanzas.com\/web\/2026\/07\/saladas-policia-de-corrientes-secuestra-motocicleta-con-pedido-de-secuestro-activo\/","title":{"rendered":"SALADAS: POLICIA DE CORRIENTES SECUESTRA MOTOCICLETA CON PEDIDO DE SECUESTRO ACTIVO"},"content":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito Primera de Saladas, realizando sus labores de prevenci\u00f3n y contralor vehicular, secuestraron una motocicleta con pedido de secuestro activo por hallarse denunciada como sustra\u00edda en la Ciudad de Corrientes.<\/p>\n<p>El procedimiento fue realizado por los citados efectivos, quienes se encontraban realizando un operativo de control, cuando identificaron a una persona mayor de edad, quien circulaba en una motocicleta \u2013 marca Honda Wave 110cc.-, la cual, con la colaboraci\u00f3n de la Direcci\u00f3n de Investigaci\u00f3n Criminal de la Ciudad de Corrientes, tras las correspondientes averiguaciones, resulto encontrarse denunciada como sustra\u00edda en una de las dependencias de esta ciudad, por lo que se procedi\u00f3 al secuestro de la misma.<\/p>\n<p>El rodado secuestrado fue puesta a disposici\u00f3n de las autoridades judiciales en turno y trasladada a la citada dependencia, donde se prosiguieron con los tramites de rigor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos policiales de la Comisaria Distrito Primera de Saladas, realizando sus labores de prevenci\u00f3n y contralor vehicular, secuestraron una motocicleta con pedido de secuestro activo por hallarse denunciada como sustra\u00edda en la Ciudad de Corrientes. El procedimiento fue realizado por los citados efectivos, quienes se encontraban realizando un operativo de control, cuando identificaron a una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":158611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-158610","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corrientes"],"_links":{"self":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/comments?post=158610"}],"version-history":[{"count":1,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158610\/revisions"}],"predecessor-version":[{"id":158612,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/posts\/158610\/revisions\/158612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media\/158611"}],"wp:attachment":[{"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/media?parent=158610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/categories?post=158610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaesperanzas.com\/web\/wp-json\/wp\/v2\/tags?post=158610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}